{"id":25788,"date":"2026-06-22T09:35:41","date_gmt":"2026-06-22T12:35:41","guid":{"rendered":"https:\/\/activecorp.com.br\/ajuda\/?p=25788"},"modified":"2026-06-24T13:47:45","modified_gmt":"2026-06-24T16:47:45","slug":"novidades-active-trans-versao-259-7","status":"publish","type":"post","link":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/","title":{"rendered":"Novidades Active Trans &#8211; Vers\u00e3o 259.7"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\">CIOT e&nbsp;\u202fVale-Ped\u00e1gio&nbsp;no Active Trans: o que mudou?&nbsp;&nbsp;<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7-700x394.png\" alt=\"\" class=\"wp-image-25794\" style=\"aspect-ratio:1.7766561514195585;width:688px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h1 class=\"wp-block-heading has-medium-font-size\"><strong>Zero retrabalho: Emita o Vale-Ped\u00e1gio integrado a e-Frete<\/strong>&nbsp;<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Agora voc\u00ea pode emitir o Vale-Ped\u00e1gio obrigat\u00f3rio sem precisar acessar portais externos ou preencher informa\u00e7\u00f5es j\u00e1 cadastradas no sistema.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a nova integra\u00e7\u00e3o entre o Active Trans e a e-Frete, os dados da viagem s\u00e3o enviados automaticamente para a emiss\u00e3o do Vale-Ped\u00e1gio, deixando o processo mais r\u00e1pido, seguro e alinhado \u00e0s exig\u00eancias da ANTT.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udd0d O que mudou?<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os dados j\u00e1 cadastrados na opera\u00e7\u00e3o s\u00e3o utilizados automaticamente na solicita\u00e7\u00e3o.&nbsp;&nbsp;<\/li>\n\n\n\n<li>O retorno da emiss\u00e3o \u00e9 processado pelo sistema sem interven\u00e7\u00e3o manual.&nbsp;&nbsp;<\/li>\n\n\n\n<li>As informa\u00e7\u00f5es do Vale-Ped\u00e1gio ficam registradas na opera\u00e7\u00e3o, incluindo:\n<ul class=\"wp-block-list\">\n<li>N\u00famero do vale-ped\u00e1gio;&nbsp;<\/li>\n\n\n\n<li>Valor emitido;&nbsp;<\/li>\n\n\n\n<li>Status da emiss\u00e3o;&nbsp;<\/li>\n\n\n\n<li>Data de emiss\u00e3o;&nbsp;<\/li>\n\n\n\n<li>Comprovantes e informa\u00e7\u00f5es complementares disponibilizadas pela operadora.&nbsp;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>A Tela 390 passa a exibir o status atualizado da emiss\u00e3o e os dados do vale gerado.&nbsp;&nbsp;<\/li>\n\n\n\n<li>O n\u00famero do Vale-Ped\u00e1gio fica dispon\u00edvel para utiliza\u00e7\u00e3o na emiss\u00e3o do MDF-e.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Tamb\u00e9m foram implementados tratamentos para retorno de erros, rejei\u00e7\u00f5es e falhas de comunica\u00e7\u00e3o.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Para utilizar a integra\u00e7\u00e3o, basta cadastrar as credenciais em&nbsp;<strong>301 &#8211; Par\u00e2metros Gerais &gt; Conta Corrente de Motorista \/ CIOT &gt; E-Frete<\/strong>.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Muito legal, n\u00e9?!&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"700\" height=\"476\" src=\"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/image_ciot-700x476.jpg\" alt=\"\" class=\"wp-image-25804\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Gerencie todo o ciclo do CIOT sem acessar outros sistemas<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea usa a\u00a0Rodoclube\u00a0para a emiss\u00e3o do CIOT, temos novidades!\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora a emiss\u00e3o, o cancelamento e o encerramento do CIOT podem ser realizados diretamente&nbsp;no&nbsp;Active Trans, com mais agilidade, controle e seguran\u00e7a para a&nbsp;sua&nbsp;opera\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a nova integra\u00e7\u00e3o com a\u00a0Rodoclube,\u00a0voc\u00ea\u00a0utiliza automaticamente os dados j\u00e1 cadastrados\u00a0para gerenciar todo o ciclo do CIOT\u00a0no Active Trans, eliminando retrabalho e reduzindo erros entre documentos e processos.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udd0d O que mudou?&nbsp;<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O Active Trans passa a emitir o CIOT automaticamente utilizando os dados da opera\u00e7\u00e3o de transporte.&nbsp;&nbsp;<\/li>\n\n\n\n<li>A integra\u00e7\u00e3o com a\u00a0Rodoclube\u00a0permite a emiss\u00e3o, cancelamento e encerramento do CIOT.\u00a0<\/li>\n\n\n\n<li>O c\u00f3digo do CIOT e seu status s\u00e3o registrados automaticamente no sistema.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Os retornos da\u00a0Rodoclube\u00a0s\u00e3o sincronizados automaticamente, mantendo os status atualizados.\u00a0\u00a0<\/li>\n\n\n\n<li>Foram adicionados mecanismos de auditoria para registrar:\n<ul class=\"wp-block-list\">\n<li>Requisi\u00e7\u00f5es enviadas;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Respostas recebidas;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Altera\u00e7\u00f5es de status;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Hist\u00f3rico das opera\u00e7\u00f5es.&nbsp;&nbsp;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Os dados utilizados na integra\u00e7\u00e3o s\u00e3o obtidos diretamente dos cadastros j\u00e1 existentes no sistema.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Tamb\u00e9m foram implementados tratamentos para erros, rejei\u00e7\u00f5es e falhas de comunica\u00e7\u00e3o.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Com isso, voc\u00ea ter\u00e1 mais agilidade em sua opera\u00e7\u00e3o e estar\u00e1 em conformidade com as exig\u00eancias da ANTT.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para saber mais detalhes sobre as melhorias,\u202f\u00e9 s\u00f3 entrar em contato com a&nbsp;<a href=\"https:\/\/suporte.activecorp.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">equipe de suporte<\/a>!&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CIOT e&nbsp;\u202fVale-Ped\u00e1gio&nbsp;no Active Trans: o que mudou?&nbsp;&nbsp; Zero retrabalho: Emita o Vale-Ped\u00e1gio integrado a e-Frete&nbsp; Agora voc\u00ea pode emitir o Vale-Ped\u00e1gio obrigat\u00f3rio sem precisar acessar portais externos ou preencher informa\u00e7\u00f5es j\u00e1 cadastradas no sistema.&nbsp; Com a nova integra\u00e7\u00e3o entre o Active Trans e a e-Frete, os dados da viagem s\u00e3o enviados automaticamente para a emiss\u00e3o [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[333,623],"tags":[],"class_list":["post-25788","post","type-post","status-publish","format-standard","hentry","category-activ_etrans","category-novidadesat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novidades Active Trans - Vers\u00e3o 259.7 - Central de Ajuda Active Corp<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novidades Active Trans - Vers\u00e3o 259.7 - Central de Ajuda Active Corp\" \/>\n<meta property=\"og:description\" content=\"CIOT e&nbsp;\u202fVale-Ped\u00e1gio&nbsp;no Active Trans: o que mudou?&nbsp;&nbsp; Zero retrabalho: Emita o Vale-Ped\u00e1gio integrado a e-Frete&nbsp; Agora voc\u00ea pode emitir o Vale-Ped\u00e1gio obrigat\u00f3rio sem precisar acessar portais externos ou preencher informa\u00e7\u00f5es j\u00e1 cadastradas no sistema.&nbsp; Com a nova integra\u00e7\u00e3o entre o Active Trans e a e-Frete, os dados da viagem s\u00e3o enviados automaticamente para a emiss\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Central de Ajuda Active Corp\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-22T12:35:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T16:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marketing Active\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing Active\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/\"},\"author\":{\"name\":\"Marketing Active\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#\\\/schema\\\/person\\\/58a5c79950a211142883f77cc3341e4d\"},\"headline\":\"Novidades Active Trans &#8211; Vers\u00e3o 259.7\",\"datePublished\":\"2026-06-22T12:35:41+00:00\",\"dateModified\":\"2026-06-24T16:47:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/AT-259.7-700x394.png\",\"articleSection\":[\"Active Trans\",\"Novidades AT\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/\",\"url\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/\",\"name\":\"Novidades Active Trans - Vers\u00e3o 259.7 - Central de Ajuda Active Corp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/AT-259.7-700x394.png\",\"datePublished\":\"2026-06-22T12:35:41+00:00\",\"dateModified\":\"2026-06-24T16:47:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/AT-259.7.png\",\"contentUrl\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/AT-259.7.png\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/novidades-active-trans-versao-259-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novidades Active Trans &#8211; Vers\u00e3o 259.7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#website\",\"url\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/\",\"name\":\"Ajuda ActiveCorp\",\"description\":\"Aqui voc\u00ea encontra v\u00eddeos e tutoriais dos produtos ActiveCorp\",\"publisher\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#organization\",\"name\":\"ActiveCorp\",\"url\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo_activecorp.png\",\"contentUrl\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo_activecorp.png\",\"width\":298,\"height\":102,\"caption\":\"ActiveCorp\"},\"image\":{\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/activecorp.com.br\\\/ajuda\\\/#\\\/schema\\\/person\\\/58a5c79950a211142883f77cc3341e4d\",\"name\":\"Marketing Active\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c713ca6a9c85f0c04b53efdb61724a2c95eed87477470d4276245e99fbc2fe4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c713ca6a9c85f0c04b53efdb61724a2c95eed87477470d4276245e99fbc2fe4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c713ca6a9c85f0c04b53efdb61724a2c95eed87477470d4276245e99fbc2fe4?s=96&d=mm&r=g\",\"caption\":\"Marketing Active\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novidades Active Trans - Vers\u00e3o 259.7 - Central de Ajuda Active Corp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/","og_locale":"pt_BR","og_type":"article","og_title":"Novidades Active Trans - Vers\u00e3o 259.7 - Central de Ajuda Active Corp","og_description":"CIOT e&nbsp;\u202fVale-Ped\u00e1gio&nbsp;no Active Trans: o que mudou?&nbsp;&nbsp; Zero retrabalho: Emita o Vale-Ped\u00e1gio integrado a e-Frete&nbsp; Agora voc\u00ea pode emitir o Vale-Ped\u00e1gio obrigat\u00f3rio sem precisar acessar portais externos ou preencher informa\u00e7\u00f5es j\u00e1 cadastradas no sistema.&nbsp; Com a nova integra\u00e7\u00e3o entre o Active Trans e a e-Frete, os dados da viagem s\u00e3o enviados automaticamente para a emiss\u00e3o [&hellip;]","og_url":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/","og_site_name":"Central de Ajuda Active Corp","article_published_time":"2026-06-22T12:35:41+00:00","article_modified_time":"2026-06-24T16:47:45+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7.png","type":"image\/png"}],"author":"Marketing Active","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marketing Active","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#article","isPartOf":{"@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/"},"author":{"name":"Marketing Active","@id":"https:\/\/activecorp.com.br\/ajuda\/#\/schema\/person\/58a5c79950a211142883f77cc3341e4d"},"headline":"Novidades Active Trans &#8211; Vers\u00e3o 259.7","datePublished":"2026-06-22T12:35:41+00:00","dateModified":"2026-06-24T16:47:45+00:00","mainEntityOfPage":{"@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/activecorp.com.br\/ajuda\/#organization"},"image":{"@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#primaryimage"},"thumbnailUrl":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7-700x394.png","articleSection":["Active Trans","Novidades AT"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/","url":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/","name":"Novidades Active Trans - Vers\u00e3o 259.7 - Central de Ajuda Active Corp","isPartOf":{"@id":"https:\/\/activecorp.com.br\/ajuda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#primaryimage"},"image":{"@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#primaryimage"},"thumbnailUrl":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7-700x394.png","datePublished":"2026-06-22T12:35:41+00:00","dateModified":"2026-06-24T16:47:45+00:00","breadcrumb":{"@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#primaryimage","url":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7.png","contentUrl":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2026\/06\/AT-259.7.png","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/activecorp.com.br\/ajuda\/novidades-active-trans-versao-259-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/activecorp.com.br\/ajuda\/"},{"@type":"ListItem","position":2,"name":"Novidades Active Trans &#8211; Vers\u00e3o 259.7"}]},{"@type":"WebSite","@id":"https:\/\/activecorp.com.br\/ajuda\/#website","url":"https:\/\/activecorp.com.br\/ajuda\/","name":"Ajuda ActiveCorp","description":"Aqui voc\u00ea encontra v\u00eddeos e tutoriais dos produtos ActiveCorp","publisher":{"@id":"https:\/\/activecorp.com.br\/ajuda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/activecorp.com.br\/ajuda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/activecorp.com.br\/ajuda\/#organization","name":"ActiveCorp","url":"https:\/\/activecorp.com.br\/ajuda\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/activecorp.com.br\/ajuda\/#\/schema\/logo\/image\/","url":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2019\/08\/logo_activecorp.png","contentUrl":"https:\/\/activecorp.com.br\/ajuda\/wp-content\/uploads\/2019\/08\/logo_activecorp.png","width":298,"height":102,"caption":"ActiveCorp"},"image":{"@id":"https:\/\/activecorp.com.br\/ajuda\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/activecorp.com.br\/ajuda\/#\/schema\/person\/58a5c79950a211142883f77cc3341e4d","name":"Marketing Active","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0c713ca6a9c85f0c04b53efdb61724a2c95eed87477470d4276245e99fbc2fe4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0c713ca6a9c85f0c04b53efdb61724a2c95eed87477470d4276245e99fbc2fe4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c713ca6a9c85f0c04b53efdb61724a2c95eed87477470d4276245e99fbc2fe4?s=96&d=mm&r=g","caption":"Marketing Active"}}]}},"_links":{"self":[{"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/posts\/25788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/comments?post=25788"}],"version-history":[{"count":5,"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/posts\/25788\/revisions"}],"predecessor-version":[{"id":25811,"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/posts\/25788\/revisions\/25811"}],"wp:attachment":[{"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/media?parent=25788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/categories?post=25788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/activecorp.com.br\/ajuda\/wp-json\/wp\/v2\/tags?post=25788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}